{"id":877,"date":"2020-10-06T11:00:36","date_gmt":"2020-10-06T11:00:36","guid":{"rendered":"https:\/\/shop.alma-fashion.com\/?page_id=877"},"modified":"2024-10-22T10:48:21","modified_gmt":"2024-10-22T10:48:21","slug":"nalog-maska-kosula","status":"publish","type":"page","link":"https:\/\/shop.alma-fashion.com\/en\/nalog-maska-kosula\/","title":{"rendered":"\u041d\u0430\u043b\u043e\u0433 &#8211; \u043c\u0430\u0448\u043a\u0430 \u043a\u043e\u0448\u0443\u043b\u0430"},"content":{"rendered":"\n<style>\ntd{\n    border: 1px solid;\n}\n<\/style>\n<div class=\"row\"  id=\"row-141901470\">\n\n\n\t<div id=\"col-1378345242\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-2230\"><form id=\"wpforms-form-2230\" class=\"wpforms-validate wpforms-form\" data-formid=\"2230\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/877?wpforms_form_id=2230\" data-token=\"4908006c7edf4a8a6c2f1b72849691f4\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-2230-field_25-container\" class=\"wpforms-field wpforms-field-divider\" data-field-id=\"25\"><h3 id=\"wpforms-2230-field_25\" name=\"wpforms[fields][25]\">\u0418\u043d\u0444\u043e\u0440\u043c\u0430\u0446\u0438\u0438 \u0437\u0430 \u0432\u0430\u0441<\/h3><\/div><div id=\"wpforms-2230-field_3-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-2230-field_3\">\u0418\u043c\u0435 \u0438 \u043f\u0440\u0435\u0437\u0438\u043c\u0435 <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-2230-field_3\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][3]\" required><\/div><div id=\"wpforms-2230-field_4-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-2230-field_4\">\u0415-\u043f\u043e\u0448\u0442\u0430 <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-2230-field_4\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][4]\" required><\/div><div id=\"wpforms-2230-field_26-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"26\"><label class=\"wpforms-field-label\" for=\"wpforms-2230-field_26\">\u0424\u0438\u0440\u043c\u0430<\/label><input type=\"text\" id=\"wpforms-2230-field_26\" class=\"wpforms-field-large\" name=\"wpforms[fields][26]\" ><\/div><div id=\"wpforms-2230-field_5-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-2230-field_5\">\u0412\u0430\u0448\u0430 \u043f\u043e\u0440\u0430\u043a\u0430<\/label><textarea id=\"wpforms-2230-field_5\" class=\"wpforms-field-medium\" name=\"wpforms[fields][5]\" ><\/textarea><\/div><div id=\"wpforms-2230-field_24-container\" class=\"wpforms-field wpforms-field-divider\" data-field-id=\"24\"><h3 id=\"wpforms-2230-field_24\" name=\"wpforms[fields][24]\">\u0418\u043d\u0444\u043e\u0440\u043c\u0430\u0446\u0438\u0438 \u0437\u0430 \u043d\u0430\u043b\u043e\u0433\u043e\u0442<\/h3><\/div><div id=\"wpforms-2230-field_9-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-2230-field_9\">\u041a\u043e\u043b\u0438\u0447\u0438\u043d\u0430  <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"number\" pattern=\"\\d*\" id=\"wpforms-2230-field_9\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][9]\" placeholder=\"300\" required><div class=\"wpforms-field-description\">\u0418\u0417\u0412\u0415\u0421\u0422\u0423\u0412\u0410\u040a\u0415: \u041c\u0438\u043d\u0438\u043c\u0430\u043b\u043d\u0430\u0442\u0430 \u043a\u043e\u043b\u0438\u0447\u0438\u043d\u0430 \u043d\u0430 \u043d\u0430\u0440\u0430\u0447\u043a\u0430\u0442\u0430 \u0435 300<\/div><\/div><div id=\"wpforms-2230-field_8-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-2230-field_8\">\u0411\u043e\u0458\u0430 \u043d\u0430 \u043c\u0430\u0442\u0435\u0440\u0438\u0458\u0430\u043b<\/label><input type=\"text\" id=\"wpforms-2230-field_8\" class=\"wpforms-field-large\" name=\"wpforms[fields][8]\" ><div class=\"wpforms-field-description\">\u0418\u0417\u0412\u0415\u0421\u0422\u0423\u0412\u0410\u040a\u0415: \u0410\u043a\u043e \u043f\u043e\u043b\u0435\u0442\u043e \u0435 \u043f\u0440\u0430\u0437\u043d\u043e, \u0437\u0430\u0434\u0430\u0434\u0435\u043d\u0430\u0442\u0430 \u0431\u043e\u0458\u0430 \u0435 \u0411\u0415\u041b\u0410.<\/div><\/div><div id=\"wpforms-2230-field_30-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"30\"><label class=\"wpforms-field-label\" for=\"wpforms-2230-field_30\">\u0422\u0438\u043f \u043d\u0430 \u043c\u0430\u0442\u0435\u0440\u0438\u0458\u0430\u043b<\/label><input type=\"text\" id=\"wpforms-2230-field_30\" class=\"wpforms-field-large\" name=\"wpforms[fields][30]\" ><\/div><div id=\"wpforms-2230-field_10-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"10\"><label class=\"wpforms-field-label\" for=\"wpforms-2230-field_10\">\u0411\u043e\u0458\u0430 \u043d\u0430 \u043a\u043e\u043d\u0435\u0446<\/label><input type=\"text\" id=\"wpforms-2230-field_10\" class=\"wpforms-field-large\" name=\"wpforms[fields][10]\" ><div class=\"wpforms-field-description\">\u0418\u0417\u0412\u0415\u0421\u0422\u0423\u0412\u0410\u040a\u0415: \u0410\u043a\u043e \u043f\u043e\u043b\u0435\u0442\u043e \u0435 \u043f\u0440\u0430\u0437\u043d\u043e, \u0437\u0430\u0434\u0430\u0434\u0435\u043d\u0430\u0442\u0430 \u0431\u043e\u0458\u0430 \u0435 \u0411\u0415\u041b\u0410.<\/div><\/div><div id=\"wpforms-2230-field_11-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"11\"><label class=\"wpforms-field-label\" for=\"wpforms-2230-field_11\">\u0411\u043e\u0458\u0430 \u043d\u0430 \u043a\u043e\u043f\u0447\u0435<\/label><input type=\"text\" id=\"wpforms-2230-field_11\" class=\"wpforms-field-large\" name=\"wpforms[fields][11]\" ><div class=\"wpforms-field-description\">\u0418\u0417\u0412\u0415\u0421\u0422\u0423\u0412\u0410\u040a\u0415: \u0410\u043a\u043e \u043f\u043e\u043b\u0435\u0442\u043e \u0435 \u043f\u0440\u0430\u0437\u043d\u043e, \u0437\u0430\u0434\u0430\u0434\u0435\u043d\u0430\u0442\u0430 \u0431\u043e\u0458\u0430 \u0435 \u0411\u0415\u041b\u0410.<\/div><\/div><div id=\"wpforms-2230-field_12-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-id=\"12\"><label class=\"wpforms-field-label\" for=\"wpforms-2230-field_12\">\u0413\u043e\u043b\u0435\u043c\u0438\u043d\u0430 \u043d\u0430 \u041a\u043e\u043f\u0447\u0435<\/label><select id=\"wpforms-2230-field_12\" class=\"wpforms-field-large choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-large\" data-search-enabled=\"\" name=\"wpforms[fields][12]\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>14&quot;(9 mm)<\/option><option value=\"14&quot;(9 mm)\" >14&quot;(9 mm)<\/option><option value=\"16&quot;(10,2 mm)\" >16&quot;(10,2 mm)<\/option><option value=\"17&quot;(11 mm)\" >17&quot;(11 mm)<\/option><option value=\"18&quot;(11,5 mm)\" >18&quot;(11,5 mm)<\/option><option value=\"20&quot;(12,8 mm)\" >20&quot;(12,8 mm)<\/option><\/select><div class=\"wpforms-field-description\">\u0418\u0417\u0412\u0415\u0421\u0422\u0423\u0412\u0410\u040a\u0415: \u0410\u043a\u043e \u043f\u043e\u043b\u0435\u0442\u043e \u0435 \u043f\u0440\u0430\u0437\u043d\u043e, \u0441\u0442\u0430\u043d\u0434\u0430\u0440\u0434\u043d\u0430\u0442\u0430 \u0433\u043e\u043b\u0435\u043c\u0438\u043d\u0430 \u043d\u0430 \u043a\u043e\u043f\u0447\u0435\u0442\u043e \u0435 16\".<\/div><\/div><div id=\"wpforms-2230-field_27-container\" class=\"wpforms-field wpforms-field-divider\" data-field-id=\"27\"><h3 id=\"wpforms-2230-field_27\" name=\"wpforms[fields][27]\">\u0414\u043e\u043f\u043e\u043b\u043d\u0438\u0442\u0435\u043b\u043d\u0438 \u0435\u043b\u0435\u043c\u0435\u043d\u0442\u0438<\/h3><\/div><div id=\"wpforms-2230-field_28-container\" class=\"wpforms-field wpforms-field-radio\" data-field-id=\"28\"><label class=\"wpforms-field-label\" for=\"wpforms-2230-field_28\">\u041b\u0430\u0458\u0441\u043d\u0430<\/label><ul id=\"wpforms-2230-field_28\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-2230-field_28_1\" name=\"wpforms[fields][28]\" value=\"\u041d\u0430\u0448\u0438\u0432\u043d\u0430 \u043b\u0430\u0458\u0441\u043d\u0430 \u0441\u043e \u0432\u0438\u0434\u043b\u0438\u0432\u0438 \u043a\u043e\u043f\u0447\u0438\u045a\u0430\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2230-field_28_1\">\u041d\u0430\u0448\u0438\u0432\u043d\u0430 \u043b\u0430\u0458\u0441\u043d\u0430 \u0441\u043e \u0432\u0438\u0434\u043b\u0438\u0432\u0438 \u043a\u043e\u043f\u0447\u0438\u045a\u0430<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-2230-field_28_2\" name=\"wpforms[fields][28]\" value=\"\u0421\u043a\u0440\u0438\u0435\u043d\u0430 \u043b\u0430\u0458\u0441\u043d\u0430 - \u043f\u0440\u0435\u043a\u043b\u043e\u043f \u0438 \u0441\u043e \u043d\u0435\u0432\u0438\u0434\u043b\u0438\u0432\u0438 \u043a\u043e\u043f\u0447\u0438\u045a\u0430\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2230-field_28_2\">\u0421\u043a\u0440\u0438\u0435\u043d\u0430 \u043b\u0430\u0458\u0441\u043d\u0430 - \u043f\u0440\u0435\u043a\u043b\u043e\u043f \u0438 \u0441\u043e \u043d\u0435\u0432\u0438\u0434\u043b\u0438\u0432\u0438 \u043a\u043e\u043f\u0447\u0438\u045a\u0430<\/label><\/li><\/ul><\/div><div id=\"wpforms-2230-field_2-container\" class=\"wpforms-field wpforms-field-radio collar-type\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-2230-field_2\">\u0422\u0438\u043f \u043d\u0430 \u0458\u0430\u043a\u0430<\/label><ul id=\"wpforms-2230-field_2\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-2230-field_2_1\" name=\"wpforms[fields][2]\" value=\"\u041a\u0435\u043d\u0442 \u0458\u0430\u043a\u0430\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2230-field_2_1\">\u041a\u0435\u043d\u0442 \u0458\u0430\u043a\u0430<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-2230-field_2_2\" name=\"wpforms[fields][2]\" value=\"Hidden Button Down\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2230-field_2_2\">Hidden Button Down<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-2230-field_2_3\" name=\"wpforms[fields][2]\" value=\"Buttondown\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2230-field_2_3\">Buttondown<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-2230-field_2_4\" name=\"wpforms[fields][2]\" value=\"\u0420\u0443\u0441\u043a\u0430 \u0458\u0430\u043a\u0430\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2230-field_2_4\">\u0420\u0443\u0441\u043a\u0430 \u0458\u0430\u043a\u0430<\/label><\/li><\/ul><\/div><div id=\"wpforms-2230-field_29-container\" class=\"wpforms-field wpforms-field-radio\" data-field-id=\"29\"><label class=\"wpforms-field-label\" for=\"wpforms-2230-field_29\">\u0420\u0430\u043a\u0430\u0432\u0438<\/label><ul id=\"wpforms-2230-field_29\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-2230-field_29_1\" name=\"wpforms[fields][29]\" value=\"\u041d\u0430 \u0434\u043e\u043b\u0433\u0438 \u0440\u0430\u043a\u0430\u0432\u0438\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2230-field_29_1\">\u041d\u0430 \u0434\u043e\u043b\u0433\u0438 \u0440\u0430\u043a\u0430\u0432\u0438<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-2230-field_29_2\" name=\"wpforms[fields][29]\" value=\"\u041d\u0430 \u043a\u0440\u0430\u0442\u043a\u0438 \u0440\u0430\u043a\u0430\u0432\u0438\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2230-field_29_2\">\u041d\u0430 \u043a\u0440\u0430\u0442\u043a\u0438 \u0440\u0430\u043a\u0430\u0432\u0438<\/label><\/li><\/ul><\/div><div id=\"wpforms-2230-field_21-container\" class=\"wpforms-field wpforms-field-radio\" data-field-id=\"21\"><label class=\"wpforms-field-label\" for=\"wpforms-2230-field_21\">\u0418\u0437\u0431\u043e\u0440 \u043d\u0430 \u0444\u0438\u0442<\/label><ul id=\"wpforms-2230-field_21\"><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-2230-field_21_2\" name=\"wpforms[fields][21]\" value=\"Normal fit\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2230-field_21_2\">Normal fit<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-2230-field_21_3\" name=\"wpforms[fields][21]\" value=\"Slim fit\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2230-field_21_3\">Slim fit<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-2230-field_21_4\" name=\"wpforms[fields][21]\" value=\"Classic fit\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2230-field_21_4\">Classic fit<\/label><\/li><\/ul><\/div><div id=\"wpforms-2230-field_22-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-3-columns wpforms-conditional-trigger\" data-field-id=\"22\"><label class=\"wpforms-field-label\" for=\"wpforms-2230-field_22\">\u0428\u0442\u0430\u043c\u043f\u0430 \u0438 \u0432\u0435\u0437\u0435\u045a\u0435<\/label><ul id=\"wpforms-2230-field_22\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-2230-field_22_1\" name=\"wpforms[fields][22]\" value=\"\u0412\u0435\u0437\u0435\u045a\u0435\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2230-field_22_1\">\u0412\u0435\u0437\u0435\u045a\u0435<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-2230-field_22_2\" name=\"wpforms[fields][22]\" value=\"\u041f\u0440\u0438\u043d\u0442\u0430\u045a\u0435\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2230-field_22_2\">\u041f\u0440\u0438\u043d\u0442\u0430\u045a\u0435<\/label><\/li><\/ul><\/div><div id=\"wpforms-2230-field_20-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-3-columns wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger\" data-field-id=\"20\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-2230-field_20\">\u041f\u043e\u0437\u0438\u0446\u0438\u0458\u0430<\/label><ul id=\"wpforms-2230-field_20\" class=\"wpforms-image-choices wpforms-image-choices-modern\"><li class=\"choice-1 depth-1 wpforms-image-choices-item\"><label class=\"wpforms-field-label-inline\" for=\"wpforms-2230-field_20_1\" tabindex=\"0\"><span class=\"wpforms-image-choices-image\"><img decoding=\"async\" src=\"https:\/\/shop.alma-fashion.com\/wp-content\/uploads\/2021\/02\/gradi-vez.jpg\" alt=\"\u0413\u0440\u0430\u0434\u0430\" title=\"\u0413\u0440\u0430\u0434\u0430\"><\/span><input type=\"checkbox\" id=\"wpforms-2230-field_20_1\" class=\"wpforms-screen-reader-element\" name=\"wpforms[fields][20][]\" value=\"\u0413\u0440\u0430\u0434\u0430\" tabindex=\"-1\"  ><span class=\"wpforms-image-choices-label\">\u0413\u0440\u0430\u0434\u0430<\/span><\/label><\/li><li class=\"choice-2 depth-1 wpforms-image-choices-item\"><label class=\"wpforms-field-label-inline\" for=\"wpforms-2230-field_20_2\" tabindex=\"0\"><span class=\"wpforms-image-choices-image\"><img decoding=\"async\" src=\"https:\/\/shop.alma-fashion.com\/wp-content\/uploads\/2021\/02\/manzeta-vez.jpg\" alt=\"\u041c\u0430\u043d\u0436\u0435\u0442\u0430\" title=\"\u041c\u0430\u043d\u0436\u0435\u0442\u0430\"><\/span><input type=\"checkbox\" id=\"wpforms-2230-field_20_2\" class=\"wpforms-screen-reader-element\" name=\"wpforms[fields][20][]\" value=\"\u041c\u0430\u043d\u0436\u0435\u0442\u0430\" tabindex=\"-1\"  ><span class=\"wpforms-image-choices-label\">\u041c\u0430\u043d\u0436\u0435\u0442\u0430<\/span><\/label><\/li><li class=\"choice-4 depth-1 wpforms-image-choices-item\"><label class=\"wpforms-field-label-inline\" for=\"wpforms-2230-field_20_4\" tabindex=\"0\"><span class=\"wpforms-image-choices-image\"><img decoding=\"async\" src=\"https:\/\/shop.alma-fashion.com\/wp-content\/uploads\/2021\/02\/BelaBeli-collar.jpg\" alt=\"\u0408\u0430\u043a\u0430\" title=\"\u0408\u0430\u043a\u0430\"><\/span><input type=\"checkbox\" id=\"wpforms-2230-field_20_4\" class=\"wpforms-screen-reader-element\" name=\"wpforms[fields][20][]\" value=\"\u0408\u0430\u043a\u0430\" tabindex=\"-1\"  ><span class=\"wpforms-image-choices-label\">\u0408\u0430\u043a\u0430<\/span><\/label><\/li><\/ul><\/div><div id=\"wpforms-2230-field_16-container\" class=\"wpforms-field wpforms-field-file-upload wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"16\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-2230-field_16\">\u041f\u0440\u0438\u043a\u0430\u0447\u0438 \u0434\u0430\u0442\u043e\u0442\u0435\u043a\u0430<\/label><div class=\"wpforms-uploader\"\n\tdata-field-id=\"16\"\n\tdata-form-id=\"2230\"\n\tdata-input-name=\"wpforms_2230_16\"\n\tdata-extensions=\"jpg,jpeg,jpe,gif,png,bmp,tiff,tif,webp,avif,ico,heic,heif,heics,heifs,asf,asx,wmv,wmx,wm,avi,divx,mov,qt,mpeg,mpg,mpe,mp4,m4v,ogv,webm,mkv,3gp,3gpp,3g2,3gp2,txt,asc,c,cc,h,srt,csv,tsv,ics,rtx,css,vtt,mp3,m4a,m4b,aac,ra,ram,wav,ogg,oga,flac,mid,midi,wma,wax,mka,rtf,pdf,class,tar,zip,gz,gzip,rar,7z,psd,xcf,doc,pot,pps,ppt,wri,xla,xls,xlt,xlw,mpp,docx,docm,dotx,dotm,xlsx,xlsm,xlsb,xltx,xltm,xlam,pptx,pptm,ppsx,ppsm,potx,potm,ppam,sldx,sldm,onetoc,onetoc2,onepkg,oxps,xps,odt,odp,ods,odg,odc,odb,odf,wp,wpd,key,numbers,pages\"\n\tdata-max-size=\"20971520\"\n\tdata-max-file-number=\"1\"\n\tdata-post-max-size=\"20971520\"\n    data-max-parallel-uploads=\"4\"\n    data-parallel-uploads=\"true\"\n\tdata-file-chunk-size=\"2097152\">\n\t<div class=\"dz-message\">\n\t\t<svg viewBox=\"0 0 1024 1024\" focusable=\"false\" class=\"\" data-icon=\"inbox\" width=\"50px\" height=\"50px\" fill=\"#B1B1B1\" aria-hidden=\"true\"><path d=\"M885.2 446.3l-.2-.8-112.2-285.1c-5-16.1-19.9-27.2-36.8-27.2H281.2c-17 0-32.1 11.3-36.9 27.6L139.4 443l-.3.7-.2.8c-1.3 4.9-1.7 9.9-1 14.8-.1 1.6-.2 3.2-.2 4.8V830a60.9 60.9 0 0 0 60.8 60.8h627.2c33.5 0 60.8-27.3 60.9-60.8V464.1c0-1.3 0-2.6-.1-3.7.4-4.9 0-9.6-1.3-14.1zm-295.8-43l-.3 15.7c-.8 44.9-31.8 75.1-77.1 75.1-22.1 0-41.1-7.1-54.8-20.6S436 441.2 435.6 419l-.3-15.7H229.5L309 210h399.2l81.7 193.3H589.4zm-375 76.8h157.3c24.3 57.1 76 90.8 140.4 90.8 33.7 0 65-9.4 90.3-27.2 22.2-15.6 39.5-37.4 50.7-63.6h156.5V814H214.4V480.1z\"><\/path><\/svg>\n\t\t<span class=\"modern-title\">\n\t\t\tClick or drag a file to this area to upload.\t\t<\/span>\n\n\t\t\t<\/div>\n<\/div>\n<input type=\"text\" class=\"dropzone-input\"\n\tstyle=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\"\n\tid=\"wpforms-2230-field_16\"\n\tname=\"wpforms_2230_16\" >\n<\/div><div id=\"wpforms-2230-field_18-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"18\"><label class=\"wpforms-field-label\" for=\"wpforms-2230-field_18\">\u0414\u043e\u043f\u043e\u043b\u043d\u0438\u0442\u0435\u043b\u043d\u043e \u0431\u0430\u0440\u0430\u045a\u0435<\/label><textarea id=\"wpforms-2230-field_18\" class=\"wpforms-field-medium\" name=\"wpforms[fields][18]\" ><\/textarea><\/div><\/div><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"2230\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"2\"><button type=\"submit\" name=\"wpforms[submit]\" class=\"wpforms-submit \" id=\"wpforms-submit-2230\" value=\"wpforms-submit\" aria-live=\"assertive\" >\u041a\u0440\u0435\u0438\u0440\u0430\u0458\u0442\u0435 \u043d\u0430\u043b\u043e\u0433<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2004647675\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<a href=\"https:\/\/shop.alma-fashion.com\/product\/bela-kosula\/\" target=\"_self\" class=\"button primary is-small\"  >\n    <span>\u041d\u0430\u0437\u0430\u0434 \u043a\u043e\u043d \u041c\u0430\u043b\u043e\u043f\u0440\u043e\u0434\u0430\u0436\u0431\u0430<\/span>\n  <\/a>\n\n\n<a rel=\"noopener noreferrer\" href=\"https:\/\/www.alma-fashion.com\/mk\/#catalogues\" target=\"_blank\" class=\"button primary is-small\"  >\n    <span>\u0414\u043e\u0434\u0430\u0442\u043d\u0438 \u043c\u0430\u0442\u0435\u0440\u0438\u0458\u0430\u043b\u0438<\/span>\n  <\/a>\n\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1653358852\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"614\" height=\"1024\" src=\"https:\/\/shop.alma-fashion.com\/wp-content\/uploads\/2021\/03\/kosula-614x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/shop.alma-fashion.com\/wp-content\/uploads\/2021\/03\/kosula-614x1024.png 614w, https:\/\/shop.alma-fashion.com\/wp-content\/uploads\/2021\/03\/kosula-510x851.png 510w, https:\/\/shop.alma-fashion.com\/wp-content\/uploads\/2021\/03\/kosula-180x300.png 180w, https:\/\/shop.alma-fashion.com\/wp-content\/uploads\/2021\/03\/kosula-768x1281.png 768w, https:\/\/shop.alma-fashion.com\/wp-content\/uploads\/2021\/03\/kosula-921x1536.png 921w, https:\/\/shop.alma-fashion.com\/wp-content\/uploads\/2021\/03\/kosula-1228x2048.png 1228w, https:\/\/shop.alma-fashion.com\/wp-content\/uploads\/2021\/03\/kosula.png 1315w\" sizes=\"auto, (max-width: 614px) 100vw, 614px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1653358852 {\n  width: 66%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h2 style=\"text-align: left;\">\u041c\u0435\u0440\u043a\u0438<\/h2>\n<table class=\" alignleft\" width=\"970\">\n<tbody>\n<tr>\n<td width=\"415\">\u0413\u043e\u043b\u0435\u043c\u0438\u043d\u0430<\/td>\n<td width=\"108\"><strong>S<\/strong><\/td>\n<td width=\"108\"><strong>M<\/strong><\/td>\n<td width=\"108\"><strong>L<\/strong><\/td>\n<td width=\"108\"><strong>XL<\/strong><\/td>\n<td width=\"109\"><strong>XXL<\/strong><\/td>\n<\/tr>\n<tr>\n<td>\u0414\u043e\u043b\u0436\u0438\u043d\u0430 \u0433\u0440\u0431<\/td>\n<td>44.0<\/td>\n<td>46.5<\/td>\n<td>49.0<\/td>\n<td>51.5<\/td>\n<td>54.0<\/td>\n<\/tr>\n<tr>\n<td>\u0413\u0440\u0430\u0434\u0438 \u0448\u0438\u0440\u0438\u043d\u0430<\/td>\n<td>106<\/td>\n<td>114<\/td>\n<td>122<\/td>\n<td>130<\/td>\n<td>138<\/td>\n<\/tr>\n<tr>\n<td>\u041f\u043e\u043b\u043e\u0432\u0438\u043d\u0430 \u0448\u0438\u0440\u0438\u043d\u0430<\/td>\n<td>96<\/td>\n<td>104<\/td>\n<td>112<\/td>\n<td>120<\/td>\n<td>128<\/td>\n<\/tr>\n<tr>\n<td>\u0420\u0430\u043c\u043e \u0434\u043e\u043b\u0436\u0438\u043d\u0430<\/td>\n<td>15.1<\/td>\n<td>16.0<\/td>\n<td>16.9<\/td>\n<td>17.8<\/td>\n<td>18.7<\/td>\n<\/tr>\n<tr>\n<td>\u0414\u043e\u043b\u0436\u0438\u043d\u0430 \u0440\u0430\u043a\u0430\u0432<\/td>\n<td>65.3<\/td>\n<td>66.3<\/td>\n<td>67.3<\/td>\n<td>67.3<\/td>\n<td>67.8<\/td>\n<\/tr>\n<tr>\n<td>\u0411\u0438\u0446\u0435\u043f\u0441<\/td>\n<td>42.0<\/td>\n<td>43.7<\/td>\n<td>45.5<\/td>\n<td>47.0<\/td>\n<td>49.0<\/td>\n<\/tr>\n<tr>\n<td>\u041e\u0431\u0438\u043a\u043e\u043b\u043a\u0430 \u043c\u0430\u043d\u0436\u0435\u0442\u043d\u0430<\/td>\n<td>26<\/td>\n<td>26<\/td>\n<td>27<\/td>\n<td>27<\/td>\n<td>28<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: left;\">&nbsp;<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-877","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u041d\u0430\u043b\u043e\u0433 - \u043c\u0430\u0448\u043a\u0430 \u043a\u043e\u0448\u0443\u043b\u0430 - ALMA FASHION WEBSHOP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shop.alma-fashion.com\/en\/nalog-maska-kosula\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u041d\u0430\u043b\u043e\u0433 - \u043c\u0430\u0448\u043a\u0430 \u043a\u043e\u0448\u0443\u043b\u0430 - ALMA FASHION WEBSHOP\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shop.alma-fashion.com\/en\/nalog-maska-kosula\/\" \/>\n<meta property=\"og:site_name\" content=\"ALMA FASHION WEBSHOP\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-22T10:48:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shop.alma-fashion.com\\\/nalog-maska-kosula\\\/\",\"url\":\"https:\\\/\\\/shop.alma-fashion.com\\\/nalog-maska-kosula\\\/\",\"name\":\"\u041d\u0430\u043b\u043e\u0433 - \u043c\u0430\u0448\u043a\u0430 \u043a\u043e\u0448\u0443\u043b\u0430 - ALMA FASHION WEBSHOP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shop.alma-fashion.com\\\/#website\"},\"datePublished\":\"2020-10-06T11:00:36+00:00\",\"dateModified\":\"2024-10-22T10:48:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shop.alma-fashion.com\\\/nalog-maska-kosula\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shop.alma-fashion.com\\\/nalog-maska-kosula\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shop.alma-fashion.com\\\/nalog-maska-kosula\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/shop.alma-fashion.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u041d\u0430\u043b\u043e\u0433 &#8211; \u043c\u0430\u0448\u043a\u0430 \u043a\u043e\u0448\u0443\u043b\u0430\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shop.alma-fashion.com\\\/#website\",\"url\":\"https:\\\/\\\/shop.alma-fashion.com\\\/\",\"name\":\"ALMA FASHION WEBSHOP\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shop.alma-fashion.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u041d\u0430\u043b\u043e\u0433 - \u043c\u0430\u0448\u043a\u0430 \u043a\u043e\u0448\u0443\u043b\u0430 - ALMA FASHION WEBSHOP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shop.alma-fashion.com\/en\/nalog-maska-kosula\/","og_locale":"en_US","og_type":"article","og_title":"\u041d\u0430\u043b\u043e\u0433 - \u043c\u0430\u0448\u043a\u0430 \u043a\u043e\u0448\u0443\u043b\u0430 - ALMA FASHION WEBSHOP","og_url":"https:\/\/shop.alma-fashion.com\/en\/nalog-maska-kosula\/","og_site_name":"ALMA FASHION WEBSHOP","article_modified_time":"2024-10-22T10:48:21+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/shop.alma-fashion.com\/nalog-maska-kosula\/","url":"https:\/\/shop.alma-fashion.com\/nalog-maska-kosula\/","name":"\u041d\u0430\u043b\u043e\u0433 - \u043c\u0430\u0448\u043a\u0430 \u043a\u043e\u0448\u0443\u043b\u0430 - ALMA FASHION WEBSHOP","isPartOf":{"@id":"https:\/\/shop.alma-fashion.com\/#website"},"datePublished":"2020-10-06T11:00:36+00:00","dateModified":"2024-10-22T10:48:21+00:00","breadcrumb":{"@id":"https:\/\/shop.alma-fashion.com\/nalog-maska-kosula\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shop.alma-fashion.com\/nalog-maska-kosula\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/shop.alma-fashion.com\/nalog-maska-kosula\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/shop.alma-fashion.com\/"},{"@type":"ListItem","position":2,"name":"\u041d\u0430\u043b\u043e\u0433 &#8211; \u043c\u0430\u0448\u043a\u0430 \u043a\u043e\u0448\u0443\u043b\u0430"}]},{"@type":"WebSite","@id":"https:\/\/shop.alma-fashion.com\/#website","url":"https:\/\/shop.alma-fashion.com\/","name":"ALMA FASHION WEBSHOP","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shop.alma-fashion.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/shop.alma-fashion.com\/en\/wp-json\/wp\/v2\/pages\/877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.alma-fashion.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/shop.alma-fashion.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/shop.alma-fashion.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.alma-fashion.com\/en\/wp-json\/wp\/v2\/comments?post=877"}],"version-history":[{"count":1,"href":"https:\/\/shop.alma-fashion.com\/en\/wp-json\/wp\/v2\/pages\/877\/revisions"}],"predecessor-version":[{"id":23569,"href":"https:\/\/shop.alma-fashion.com\/en\/wp-json\/wp\/v2\/pages\/877\/revisions\/23569"}],"wp:attachment":[{"href":"https:\/\/shop.alma-fashion.com\/en\/wp-json\/wp\/v2\/media?parent=877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}